{"id":1535,"date":"2022-09-14T16:57:01","date_gmt":"2022-09-14T16:57:01","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1535"},"modified":"2024-09-19T17:52:50","modified_gmt":"2024-09-19T17:52:50","slug":"el-club-de-amics-de-la-pilota-de-xilxes-se-clasifica-por-primera-vez-en-la-final-del-trofeo-de-verano-de-escala-i-corda-2022","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/el-club-de-amics-de-la-pilota-de-xilxes-se-clasifica-por-primera-vez-en-la-final-del-trofeo-de-verano-de-escala-i-corda-2022\/","title":{"rendered":"El Club d&#039;Amics de la Pilota de Xilxes es classifica per primera vegada a la final del Trofeu d&#039;Estiu d&#039;Escala i Corda 2022"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1535\" data-postid=\"1535\" class=\"themify_builder_content themify_builder_content-1535 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><b>Els partits dels dos equips classificats del club es disputaran el proper 28 de juliol i 30 de juliol a les 19 hores al Trinquet de Torrent<\/b><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<p>El Club d&#039;Amics de la Pilota de Xilxes s&#039;ha classificat per primera vegada a la final de 1a categoria del Trofeu Diputaci\u00f3 de Castell\u00f3 d&#039;Escala i Corda en la catorzena edici\u00f3, conformada pels grups integrants de la Federaci\u00f3 de Pilota Valenciana.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Els partits dels dos equips classificats del club municipal es disputaran el proper 28 i 30 de juliol a les 19 hores al Trinquet de Torrent. Seran un total de vuit parelles les que lluitaran per aquest t\u00edtol mitjan\u00e7ant un format d&#039;eliminat\u00f2ries amb quarts de final, semifinals i final.<\/p>\n<p>\u00a0<\/p>\n<p>A m\u00e9s, l&#039;Ajuntament ha preparat un programa d&#039;activitats esportives per a les properes setmanes d&#039;estiu entre les quals figura el Campionat de M\u00e0del que tindr\u00e0 lloc el proper 29 de juliol a les 19 hores a la Ciutat Esportiva L&#039;Alter, on al mateix espai de l&#039;esdeveniment s&#039;habilitar\u00e0 un taller d&#039;iniciaci\u00f3 a la pilota valenciana.\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1526\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana.jpg\" class=\"wp-post-image wp-image-1536\" title=\"pilotavalenciana\" alt=\"pilotavalenciana\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana.jpg 1080w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-212x300.jpg 212w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-725x1024.jpg 725w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-768x1085.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-8x12.jpg 8w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1536,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><b>Los partidos de los dos equipos clasificados del club se disputar\u00e1n el pr\u00f3ximo 28 de julio y 30 de julio a las 19 horas en el Trinquet de Torrent<\/b><\/p> <p align=\"justify\">\u00a0<\/p>\n<article>\n<article>\n<p>El Club de Amics de la Pilota de Xilxes se ha clasificado por primera vez en la final de 1\u00aa categor\u00eda del Trofeo Diputaci\u00f3n de Castell\u00f3n de \u201cEscala i Corda\u201d en su decimocuarta edici\u00f3n, conformada por los grupos integrantes de la Federaci\u00f3n de Pilota Valenciana.\u00a0<\/p> <p>\u00a0<\/p> <p>Los partidos de los dos equipos clasificados del club municipal se disputar\u00e1n el pr\u00f3ximo 28 y 30 de julio a las 19 horas en el Trinquet de Torrent. Ser\u00e1 un total de ocho parejas las que luchar\u00e1n por este t\u00edtulo mediante un formato de eliminatorias con cuartos de final, semifinales y final.<\/p> <p>\u00a0<\/p> <p>Adem\u00e1s, el Ayuntamiento ha preparado un programa de actividades deportivas para las pr\u00f3ximas semanas de verano entre las que figura el Campeonato de M\u00e1del que tendr\u00e1 lugar el pr\u00f3ximo 29 de julio a las 19 horas en la Ciudad Deportiva L\u2019Alter, donde en el mismo espacio del evento se habilitar\u00e1 un taller de iniciaci\u00f3n a la pilota valenciana.\u00a0<\/p>\n<\/article>\n<\/article>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana.jpg\" title=\"pilotavalenciana\" alt=\"pilotavalenciana\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana.jpg 1080w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-212x300.jpg 212w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-725x1024.jpg 725w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-768x1085.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/pilotavalenciana-8x12.jpg 8w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"predecessor-version":[{"id":1538,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1535\/revisions\/1538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1536"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}