{"id":1520,"date":"2022-11-29T16:54:08","date_gmt":"2022-11-29T16:54:08","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1520"},"modified":"2024-09-19T17:53:19","modified_gmt":"2024-09-19T17:53:19","slug":"xilxes-convocara-becas-para-el-transporte-escolar-en-el-curso-academico-2022-2023","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/xilxes-convocara-becas-para-el-transporte-escolar-en-el-curso-academico-2022-2023\/","title":{"rendered":"Xilxes convocar\u00e0 beques per al transport escolar al curs acad\u00e8mic 2022-2023"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1520\" data-postid=\"1520\" class=\"themify_builder_content themify_builder_content-1520 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><b>Un cop publicada la convocat\u00f2ria, es podran consultar les bases i presentar les sol\u00b7licituds mitjan\u00e7ant la seu electr\u00f2nica de l&#039;Ajuntament\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a><\/b><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<p>L&#039;Ajuntament de Xilxes obrir\u00e0 una convocat\u00f2ria per a la sol\u00b7licitud de beques de transport escolar del curs 2022-2023 amb l&#039;objectiu de fomentar l&#039;estudi i facilitar el trasllat de l&#039;alumnat que opte per cursar estudis fora del municipi.<\/p>\n<p>\u00a0<\/p>\n<p>Aquests ajuts estan dirigits a les persones que estiguin cursant o vulguin cursar estudis oficials que no es trobin dins de l&#039;oferta educativa existent a Xilxes i poden ser tant ensenyaments universitaris com no universitaris.<\/p>\n<p>\u00a0<\/p>\n<p>El consistori destinar\u00e0 un import total de 6.000 euros a les beques. En aquest sentit, els criteris de valoraci\u00f3 que es tindran en compte per quantificar cadascuna seran la dist\u00e0ncia entre l&#039;habitatge i el centre, el tipus de titulaci\u00f3 i la situaci\u00f3 socioecon\u00f2mica, essent una quantitat m\u00e0xima de 200 euros per persona.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>El termini de presentaci\u00f3 de sol\u00b7licituds ser\u00e0 de 20 dies h\u00e0bils a comptar de l&#039;endem\u00e0 de la publicaci\u00f3 de l&#039;extracte de la convocat\u00f2ria al Butllet\u00ed Oficial de la Prov\u00edncia de Castell\u00f3. Les sol\u00b7licituds de beca es presenten a trav\u00e9s de la Seu Electr\u00f2nica de l&#039;Ajuntament de Xilxes\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a>\u00a0o, si \u00e9s de manera presencial, al registre general del consistori en horari d&#039;atenci\u00f3 al p\u00fablic.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"757\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik.jpeg\" class=\"wp-post-image wp-image-1521\" title=\"becaserik\" alt=\"becaserik\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik.jpeg 1600w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-300x142.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-1024x484.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-768x363.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-1536x727.jpeg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-18x9.jpeg 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><b>Una vez publicada la convocatoria, se podr\u00e1n consultar las bases y presentar las solicitudes a trav\u00e9s de la sede electr\u00f3nica del Ayuntamiento\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a><\/b><\/p> <p align=\"justify\">\u00a0<\/p>\n<article>\n<article>\n<p>El Ayuntamiento de Xilxes abrir\u00e1 una convocatoria para la solicitud de becas de transporte escolar del pr\u00f3ximo curso 2022-2023 con el objetivo de fomentar el estudio y facilitar el traslado del alumnado que opte por cursar estudios fuera del municipio.<\/p> <p>\u00a0<\/p> <p>Estas ayudas est\u00e1n dirigidas a las personas que est\u00e9n cursando o quieran cursar estudios oficiales que no se encuentren dentro de la oferta educativa existente en Xilxes y pueden ser tanto ense\u00f1anzas universitarias como no universitarias.<\/p> <p>\u00a0<\/p> <p>El consistorio destinar\u00e1 un importe total de 6.000 euros a las becas. En este sentido, los criterios de valoraci\u00f3n que se tendr\u00e1n en cuenta para cuantificar cada una de ellas ser\u00e1n la distancia entre la vivienda y el centro, el tipo de titulaci\u00f3n y la situaci\u00f3n socioecon\u00f3mica, siendo una cantidad m\u00e1xima de 200 euros por persona.\u00a0<\/p> <p>\u00a0<\/p> <p>El plazo de presentaci\u00f3n de solicitudes ser\u00e1 de 20 d\u00edas h\u00e1biles a contar desde el d\u00eda siguiente a la publicaci\u00f3n del extracto de la convocatoria en el Bolet\u00edn Oficial de la Provincia de Castell\u00f3n. Las solicitudes de beca se presentan a trav\u00e9s de la Sede Electr\u00f3nica del Ayuntamiento de Xilxes\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a>\u00a0o, si es de manera presencial, en el registro general del consistorio en horario de atenci\u00f3n al p\u00fablico.<\/p>\n<\/article>\n<\/article>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik.jpeg\" title=\"becaserik\" alt=\"becaserik\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik.jpeg 1600w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-300x142.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-1024x484.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-768x363.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-1536x727.jpeg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/becaserik-18x9.jpeg 18w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1520"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1520\/revisions"}],"predecessor-version":[{"id":1523,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1520\/revisions\/1523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1521"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}