{"id":1484,"date":"2023-01-26T16:22:29","date_gmt":"2023-01-26T16:22:29","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1484"},"modified":"2024-09-19T17:54:50","modified_gmt":"2024-09-19T17:54:50","slug":"xilxes-consolida-la-feria-del-libro-con-una-amplia-programacion-para-este-fin-de-semana","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/xilxes-consolida-la-feria-del-libro-con-una-amplia-programacion-para-este-fin-de-semana\/","title":{"rendered":"Xilxes consolida la Fira del Llibre amb una \u00e0mplia programaci\u00f3 per aquest cap de setmana"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1484\" data-postid=\"1484\" class=\"themify_builder_content themify_builder_content-1484 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>L&#039;esdeveniment, que aquest any ha experimentat un nombre elevat de sol\u00b7licituds de participaci\u00f3, inclou 10 presentacions liter\u00e0ries i tallers<\/strong><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<p>L&#039;Ajuntament de Xilxes celebrar\u00e0 aquest cap de setmana la Fira del Llibre amb una \u00e0mplia programaci\u00f3, esdeveniment que aquest any ha experimentat un elevat nombre de sol\u00b7licituds de participaci\u00f3 i que finalment inclou un total de 10 presentacions liter\u00e0ries i tallers per a tots els p\u00fablics a les dues jornades del 6 i 7 d&#039;agost.<\/p>\n<p>\u00a0<\/p>\n<p>La fira arrencar\u00e0 a les 18.30 hores a la Pla\u00e7a l&#039;Armada amb la presentaci\u00f3 del t\u00edtol \u201cPomp\u00f3n m&#039;ensenya les emocions\u201d, de l&#039;autora Marta Roso, i oferir\u00e0 diferents propostes fins a les 22.30 hores. Aix\u00ed mateix, el p\u00fablic podr\u00e0 con\u00e8ixer obres de diferents g\u00e8neres i tem\u00e0tiques com \u201cEl cel sobre Canfranc\u201d, \u201cYogaventuras\u201d, \u201cDespertar a S\u00f2ria\u201d, \u201cBitxo bola\u201d, \u201cExercicis per millorar la mem\u00f2ria\u201d, \u201cEducar per al col\u00b7lapse\u201d, \u201cContes de la ciutat adormida\u201d, \u201cLes nostres confessions a la confessi\u00f3\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>A m\u00e9s, s&#039;oferir\u00e0 un taller de ioga infantil i diversos autors com ara Victoria Peset, Julio Garc\u00eda Robles, Rosabel Pe\u00f1arroja, Amelia D\u00edaz, Mar\u00eda Luisa Benedicto i Susana Granell signaran els seus llibres al p\u00fablic.<\/p>\n<p>\u00a0<\/p>\n<p>La iniciativa pret\u00e9n oferir espais culturals a ve\u00efns i visitants, aix\u00ed com donar suport a lactivitat liter\u00e0ria promocionant els h\u00e0bits de lectura.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1325\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01.jpg\" class=\"wp-post-image wp-image-1485\" title=\"Fira-del-Lliure-01\" alt=\"Fira-del-Llibre-01\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01.jpg 2048w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-300x194.jpg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-1024x663.jpg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-768x497.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-1536x994.jpg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-18x12.jpg 18w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1485,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><strong>El evento, que este a\u00f1o ha experimentado un elevado n\u00famero de solicitudes de participaci\u00f3n, incluye 10 presentaciones literarias y talleres<\/strong><\/p> <p align=\"justify\">\u00a0<\/p>\n<article>\n<article>\n<p>El Ayuntamiento de Xilxes celebrar\u00e1 este fin de semana la Feria del Libro con una amplia programaci\u00f3n, evento que este a\u00f1o ha experimentado un elevado n\u00famero de solicitudes de participaci\u00f3n y que finalmente incluye un total de 10 presentaciones literarias y talleres para todos los p\u00fablicos en las dos jornadas del 6 y 7 de agosto.<\/p> <p>\u00a0<\/p> <p>La feria arrancar\u00e1 a las 18:30 horas en la Plaza la Armada con la presentaci\u00f3n del t\u00edtulo \u201cPomp\u00f3n me ense\u00f1a las emociones\u201d, de la autora Marta Roso, y ofrecer\u00e1 distintas propuestas hasta las 22:30 horas. Asimismo, el p\u00fablico podr\u00e1 conocer obras de distintos g\u00e9neros y tem\u00e1ticas como \u201cEl cielo sobre Canfranc\u201d, \u201cYogaventuras\u201d, \u201cDespertar en Soria\u201d, \u201cBicho bola\u201d, \u201cEjercicios para mejorar la memoria\u201d, \u201cEducar per al col.lapse\u201d, \u201cContes de la ciutat adormida\u201d, \u201cNuestras confesiones en la madrugada\u201d o \u201c101 cr\u00edmenes de Valencia\u201d.<\/p> <p>\u00a0<\/p> <p>Adem\u00e1s, se ofrecer\u00e1 un taller de yoga infantil y diversos autores como Victoria Peset, Julio Garc\u00eda Robles, Rosabel Pe\u00f1arroja, Amelia D\u00edaz, Mar\u00eda Luisa Benedicto y Susana Granell firmar\u00e1n sus libros al p\u00fablico.<\/p> <p>\u00a0<\/p> <p>La iniciativa pretende ofrecer espacios culturales a vecinos y visitantes, as\u00ed como apoyar la actividad literaria promocionando los h\u00e1bitos de lectura.<\/p>\n<\/article>\n<\/article>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01.jpg\" title=\"Fira-del-Llibre-01\" alt=\"Fira-del-Llibre-01\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01.jpg 2048w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-300x194.jpg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-1024x663.jpg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-768x497.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-1536x994.jpg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Fira-del-Llibre-01-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1484"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1484\/revisions"}],"predecessor-version":[{"id":1487,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1484\/revisions\/1487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}