{"id":1465,"date":"2023-08-06T16:17:49","date_gmt":"2023-08-06T16:17:49","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1465"},"modified":"2024-09-19T17:55:32","modified_gmt":"2024-09-19T17:55:32","slug":"xilxes-aprueba-en-pleno-destinar-parte-del-remanente-a-diferentes-mejoras-en-el-municipio","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/xilxes-aprueba-en-pleno-destinar-parte-del-remanente-a-diferentes-mejoras-en-el-municipio\/","title":{"rendered":"Xilxes aprova en ple destinar part del romanent a diferents millores al municipi"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1465\" data-postid=\"1465\" class=\"themify_builder_content themify_builder_content-1465 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>L&#039;Ajuntament renovar\u00e0 l&#039;enllumenat del camp de futbol i reformar\u00e0 les voreres de la Pla\u00e7a Generalitat Valenciana i el Local Mestresses de Casa<\/strong><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<p>L&#039;Ajuntament de Xilxes ha celebrat el ple ordinari del mes d&#039;agost amb l&#039;aprovaci\u00f3 de la modificaci\u00f3 de cr\u00e8dit per dur a terme diferents millores al municipi, com la renovaci\u00f3 de l&#039;enllumenat del camp de futbol o les reformes de les voreres de la Pla\u00e7a Generalitat Valenciana i el Local Mestresses de Casa. Aix\u00ed mateix, la sessi\u00f3 ha donat llum verda al programa de Festes del Crist de la Jonquera, que se celebraran del 14 al 25 de setembre.<\/p>\n<p>\u00a0<\/p>\n<p>El consistori ha alliberat el pressupost que es va destinar a principis d&#039;aquest any per construir columbaris del cementiri per motius de terminis amb l&#039;objectiu d&#039;invertir en altres necessitats m\u00e9s urgents. D&#039;aquesta manera, els diners d&#039;aquesta actuaci\u00f3 s&#039;utilitzaran en millores com la renovaci\u00f3 del material d&#039;enllumenat del camp de futbol, que es troba en estat deficient, on s&#039;instal\u00b7lar\u00e0 al seu lloc un sistema de baix consum, per\u00f2 que aporti m\u00e9s il\u00b7luminaci\u00f3.<\/p>\n<p>\u00a0<\/p>\n<p>D&#039;altra banda, tamb\u00e9 es dur\u00e0 a terme la reforma de les voreres de la Pla\u00e7a Generalitat Valenciana a fi d&#039;augmentar-ne l&#039;accessibilitat, especialment per a usuaris amb mobilitat redu\u00efda. I, finalment, una part d&#039;aquest romanent anir\u00e0 destinada a la reforma sol\u00b7licitada per l&#039;Associaci\u00f3 Mestresses de Casa de Xilxes.<\/p>\n<p>\u00a0<\/p>\n<p>&quot;Davant la impossibilitat d&#039;adjudicar i executar la inversi\u00f3 dels columbaris, hem decidit destinar aquests cr\u00e8dits extraordinaris a altres assumptes necessaris per al municipi, per aix\u00ed no desaprofitar el romanent resultant de la bona gesti\u00f3 de l&#039;exercici anterior&quot;, ha afegit Jos\u00e9 Mart\u00ednez, batle de Xilxes.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"2031\" height=\"2048\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES.jpg\" class=\"wp-post-image wp-image-1203\" title=\"PLE_XILXES\" alt=\"PLENO_XILXES\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES.jpg 2031w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-298x300.jpg 298w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-1016x1024.jpg 1016w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-150x150.jpg 150w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-768x774.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-1523x1536.jpg 1523w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-12x12.jpg 12w\" sizes=\"auto, (max-width: 2031px) 100vw, 2031px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1203,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><strong>El Ayuntamiento renovar\u00e1 el alumbrado del campo de f\u00fatbol y reformar\u00e1 las aceras de la Plaza Generalitat Valenciana y el Local Amas de Casa<\/strong><\/p> <p align=\"justify\">\u00a0<\/p>\n<article>\n<article>\n<p>El Ayuntamiento de Xilxes ha celebrado el pleno ordinario del mes de agosto con la aprobaci\u00f3n de la modificaci\u00f3n de cr\u00e9dito para llevar a cabo diferentes mejoras en el municipio, como la renovaci\u00f3n del alumbrado del campo de f\u00fatbol o las reformas de las aceras de la Plaza Generalitat Valenciana y el Local Amas de Casa. Asimismo, la sesi\u00f3n ha dado luz verde al programa de Fiestas del Cristo de la Junquera, que se celebrar\u00e1n del 14 al 25 de septiembre.<\/p> <p>\u00a0<\/p> <p>El consistorio ha liberado el presupuesto que se destin\u00f3 a principios de este a\u00f1o para la construcci\u00f3n de columbarios del cementerio por motivos de plazos con el objetivo de invertir en otras necesidades m\u00e1s urgentes. De este modo, el dinero de esa actuaci\u00f3n se emplear\u00e1 en mejoras como la renovaci\u00f3n del material de alumbrado del campo de f\u00fatbol, que se encuentra en estado deficiente, donde se instalar\u00e1 en su lugar un sistema de bajo consumo, pero que aporte una mayor iluminaci\u00f3n.<\/p> <p>\u00a0<\/p> <p>Por otro lado, tambi\u00e9n se llevar\u00e1 a cabo la reforma de las aceras de la Plaza Generalitat Valenciana a fin de aumentar su accesibilidad, especialmente para usuarios con movilidad reducida. Y, por \u00faltimo, una parte de ese remanente ir\u00e1 destinada a la reforma solicitada por la Asociaci\u00f3n Amas de Casa de Xilxes.<\/p> <p>\u00a0<\/p> <p>\u201cAnte la imposibilidad de adjudicar y ejecutar la inversi\u00f3n de los columbarios, hemos decidido destinar esos cr\u00e9ditos extraordinarios a otros asuntos necesarios para el municipio, para as\u00ed no desaprovechar el remanente resultante de la buena gesti\u00f3n del ejercicio anterior\u201d, ha a\u00f1adido Jos\u00e9 Mart\u00ednez, alcalde de Xilxes.<\/p>\n<\/article>\n<\/article>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES.jpg\" title=\"PLENO_XILXES\" alt=\"PLENO_XILXES\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES.jpg 2031w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-298x300.jpg 298w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-1016x1024.jpg 1016w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-150x150.jpg 150w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-768x774.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-1523x1536.jpg 1523w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO_XILXES-12x12.jpg 12w\" sizes=\"(max-width: 2031px) 100vw, 2031px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1465"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1465\/revisions"}],"predecessor-version":[{"id":1467,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1465\/revisions\/1467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1203"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}