{"id":1430,"date":"2023-11-01T16:09:55","date_gmt":"2023-11-01T16:09:55","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1430"},"modified":"2024-09-19T17:56:39","modified_gmt":"2024-09-19T17:56:39","slug":"xilxes-coordina-con-el-ceip-lluis-vives-el-programa-de-extraescolares-para-este-nuevo-curso","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/xilxes-coordina-con-el-ceip-lluis-vives-el-programa-de-extraescolares-para-este-nuevo-curso\/","title":{"rendered":"Xilxes coordina amb el CEIP Llu\u00eds Vives el programa d&#039;extraescolars per a aquest nou curs"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1430\" data-postid=\"1430\" class=\"themify_builder_content themify_builder_content-1430 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>\u00a0<strong>Les inscripcions ja es poden fer a l&#039;Ajuntament i les fam\u00edlies poden optar entre activitats esportives o creatives com teatre i dibuix<\/strong><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<div id=\"ttr_page\" class=\"container\">\n<div id=\"ttr_content_and_sidebar_container\">\n<div id=\"ttr_content\" class=\"zero_column\">\n<div id=\"ttr_content_margin\" class=\"container-fluid\">\n<article class=\"ttr_post list\">\n<div class=\"ttr_post_content_inner\">\n<div class=\"ttr_article\">\n<div class=\"postcontent\">\n<p>L&#039;Ajuntament de Xilxes ha presentat al CEIP Llu\u00eds Vives la proposta d&#039;activitats extraescolars per a aquest nou curs 2022\/23 per tal de facilitar la conciliaci\u00f3 de les fam\u00edlies i oferir opcions de qualitat al mateix municipi.<\/p>\n<p>\u00a0<\/p>\n<p>El regidor d\u00b4Educaci\u00f3, Erik Segarra, acompanyat pel t\u00e8cnic municipal d\u00b4Esports, s\u00b4ha reunit amb l\u00b4equip directiu del col\u00b7legi p\u00fablic per abordar i coordinar el programa d\u00b4extraescolars, que contempla activitats esportives i de foment de la creativitat com a teatre o dibuix. \u00a0<\/p>\n<p>\u00a0<\/p>\n<p>La inversi\u00f3 per oferir aquest programa procedeix d&#039;una subvenci\u00f3 sol\u00b7licitada per l&#039;Ajuntament a la Generalitat Valenciana, per aix\u00f2 les activitats tenen un cost assequible de 10 \u20ac mensuals.<\/p>\n<p>\u00a0<\/p>\n<p>A m\u00e9s de les propostes esportives i de teatre ofertes entre setmana, el programa tamb\u00e9 inclou classes de pintura i dibuix els dissabtes al mat\u00ed. Les inscripcions ja estan obertes, per la qual cosa les fam\u00edlies interessades poden formalitzar-les al consistori.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1706\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23.jpg\" class=\"wp-post-image wp-image-1431\" title=\"cartell_extraescolars_22-23\" alt=\"cartell_extraescolars_22-23\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23.jpg 1080w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-190x300.jpg 190w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-648x1024.jpg 648w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-768x1213.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-972x1536.jpg 972w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-8x12.jpg 8w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p>\u00a0<strong>Las inscripciones ya pueden realizarse en el Ayuntamiento y las familias pueden optar entre actividades deportivas o creativas como teatro y dibujo<\/strong><\/p> <p align=\"justify\">\u00a0<\/p>\n<article>\n<article>\n<p>El Ayuntamiento de Xilxes ha presentado al CEIP Llu\u00eds Vives la propuesta de actividades extraescolares para este nuevo curso 2022\/23 con el fin de facilitar la conciliaci\u00f3n de las familias y ofrecer opciones de calidad en el propio municipio.<\/p> <p>\u00a0<\/p> <p>El concejal de Educaci\u00f3n, Erik Segarra, acompa\u00f1ado por el t\u00e9cnico municipal de Deportes, se ha reunido con el equipo directivo del colegio p\u00fablico para abordar y coordinar el programa de extraescolares, que contempla actividades deportivas y de fomento de la creatividad como teatro o dibujo. \u00a0<\/p> <p>\u00a0<\/p> <p>La inversi\u00f3n para ofrecer este programa procede de una subvenci\u00f3n solicitada por el Ayuntamiento a la Generalitat Valenciana, por lo que las actividades tienen un coste asequible de 10 \u20ac mensuales.<\/p> <p>\u00a0<\/p> <p>Adem\u00e1s de las propuestas deportivas y de teatro ofertadas entre semana, el programa tambi\u00e9n incluye clases de pintura y dibujo los s\u00e1bados por la ma\u00f1ana. Las inscripciones ya est\u00e1n abiertas, por lo que las familias interesadas pueden formalizarlas en el consistorio.<\/p>\n<\/article>\n<\/article>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23.jpg\" title=\"cartell_extraescolars_22-23\" alt=\"cartell_extraescolars_22-23\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23.jpg 1080w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-190x300.jpg 190w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-648x1024.jpg 648w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-768x1213.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-972x1536.jpg 972w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/cartell_extraescolars_22-23-8x12.jpg 8w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1430"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1430\/revisions"}],"predecessor-version":[{"id":1433,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1430\/revisions\/1433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1431"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}