{"id":1361,"date":"2024-01-19T15:39:25","date_gmt":"2024-01-19T15:39:25","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1361"},"modified":"2024-09-19T17:59:34","modified_gmt":"2024-09-19T17:59:34","slug":"la-8a-edicion-de-trixilxes-sindrafting-abre-inscripciones-el-proximo-sabado-5-de-noviembre","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/la-8a-edicion-de-trixilxes-sindrafting-abre-inscripciones-el-proximo-sabado-5-de-noviembre\/","title":{"rendered":"La 8a edici\u00f3 de TriXilxes sindrafting obre inscripcions el proper dissabte 5 de novembre"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1361\" data-postid=\"1361\" class=\"themify_builder_content themify_builder_content-1361 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><b>La prova esportiva, que se celebrar\u00e0 el proper 7 de maig del 2023, ofereix un total de 540 places als esportistes que vulguin sumar-se a l&#039;experi\u00e8ncia<\/b><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>La 8a edici\u00f3 de la prova esportiva TriXilxes sindrafting, que se celebrar\u00e0 el 7 de maig de 2023, obre les inscripcions el proper dissabte 5 de novembre. En aquesta ocasi\u00f3, s&#039;ofereix un total de 540 places als esportistes que es vulguin sumar a aquest repte organitzat pel club Trilavall juntament amb l&#039;Ajuntament de Xilxes que consta de 1500 metres de nataci\u00f3, 60 km de ciclisme (#sindrafting) i 15km de carrera a peu per finalitzar.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>La prova gaudeix d&#039;una bona repercussi\u00f3 a nivell nacional, comptant amb participants de m\u00e9s del 90% de les autonomies i alguns participants estrangers (Anglaterra, Alemanya i Litu\u00e0nia). A la darrera edici\u00f3 les inscripcions es van esgotar en menys de 23 hores, arribant a 22 minuts el 2019, com a r\u00e8cord de la prova.<\/p>\n<p>\u00a0<\/p>\n<p>L&#039;organitzaci\u00f3 de l&#039;esdeveniment vol preparar un cap de setmana esportiu, tal com es va donar a la darrera edici\u00f3, oferint una varietat d&#039;activitats el dissabte 6 de maig per a tots els p\u00fablics: fira del Corredor, recollida de dorsals, entrada de material a l&#039;\u00e0rea de transici\u00f3, activitats esportives dirigides, photocall per signar, fotomat\u00f3, entre d&#039;altres.<\/p>\n<p>\u00a0<\/p>\n<p>Aix\u00ed mateix, al triatl\u00f3 de 2023, els participants comptaran amb una polsera d&#039;acc\u00e9s per convidar un acompanyant a la tradicional festa de post-meta, amb menjar i moltes sorpreses.<\/p>\n<p>\u00a0<\/p>\n<p>La prova de triXilxes compta amb el suport de l&#039;Ajuntament de Xilxes i les poblacions ve\u00efnes per on transcorre la prova (Vall d&#039;Uix\u00f3, Moncofa, Nules, La Llosa i Almenara), a m\u00e9s de la Diputaci\u00f3 de Castell\u00f3 i la Generalitat Valenciana. Pel que fa als patrocinadors, l&#039;esdeveniment est\u00e0 recolzat per les marques 226ERS, Blumaq, Sporcks, Zone3, Raw SuperDrink, Taronges Torres, Garatge Castell\u00f3, Aigua Font Primavera, SMS Electrics, Carnes M\u00farcia i Rodrimotor.<\/p>\n<p>\u00a0Ja podeu anotar al calendari la cita d&#039;aquest dissabte 5 de novembre a les 16:00 a\u00a0<a href=\"http:\/\/www.trixilxes.com\/\">www.trixilxes.com<\/a>per inscriure-us a la 8a edici\u00f3 de la TriXilxes.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes.jpeg\" class=\"wp-post-image wp-image-1362\" title=\"Trixilxes\" alt=\"Trixilxes\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes.jpeg 1600w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-300x200.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-1024x682.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-768x512.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-1536x1023.jpeg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-18x12.jpeg 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1362,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><b>La prueba deportiva, que se celebrar\u00e1 el pr\u00f3ximo 7 de mayo de 2023, ofrece un total de 540 plazas a los deportistas que quieran sumarse a la experiencia<\/b><\/p> <p align=\"justify\">\u00a0<\/p>\n<p>La 8\u00aa edici\u00f3n de la prueba deportiva TriXilxes sindrafting, que se celebrar\u00e1 el 7 de mayo de 2023, abre las inscripciones el pr\u00f3ximo s\u00e1bado 5 de noviembre. En esta ocasi\u00f3n, se oferta un total de 540 plazas a los deportistas que quieran sumarse a este reto organizado por el club Trilavall junto con el Ayuntamiento de Xilxes que consta de 1500 metros de nataci\u00f3n, 60 km de ciclismo (#sindrafting) y 15km de carrera a pie para finalizar.\u00a0<\/p> <p>\u00a0<\/p> <p>La prueba goza de una buena repercusi\u00f3n a nivel nacional, contando con participantes de m\u00e1s del 90% de las autonom\u00edas y con algunos participantes extranjeros (Inglaterra, Alemania y Lituania). En la \u00faltima edici\u00f3n las inscripciones se agotaron en menos de 23 horas, llegando a 22 minutos en 2019, como r\u00e9cord de la prueba.<\/p> <p>\u00a0<\/p> <p>La organizaci\u00f3n del evento quiere preparar un fin de semana deportivo, tal y como se dio en la \u00faltima edici\u00f3n, ofreciendo una variedad de actividades el s\u00e1bado 6 de mayo para todos los p\u00fablicos: feria del Corredor, recogida de dorsales, entrada de material en el \u00e1rea de transici\u00f3n, actividades deportivas dirigidas, photocall para firmar, fotomat\u00f3n, entre otras.<\/p> <p>\u00a0<\/p> <p>Asimismo, en el triatl\u00f3n de 2023, los participantes contar\u00e1n con una pulsera de acceso para invitar a un acompa\u00f1ante a la tradicional fiesta de post-meta , con comida y muchas sorpresas.<\/p> <p>\u00a0<\/p> <p>La prueba de triXilxes cuenta con el apoyo del Ajuntament de Xilxes y las poblaciones vecinas por donde transcurre la prueba (La Vall d'Uix\u00f3, Moncofa, Nules, La Llosa y Almenara), adem\u00e1s de la Diputaci\u00f3 de Castell\u00f3 y la Generalitat Valenciana. En cuanto a los patrocinadores, el evento est\u00e1 respaldado por las marcas 226ERS, Blumaq, Sporcks, Zone3, Raw SuperDrink, Naranjas Torres, Garage Castell\u00f3n, Agua Fuente Primavera, SMS Electrics, Carnes Murcia y Rodrimotor.<\/p> <p>\u00a0Ya pod\u00e9is anotar en el calendario la cita de este s\u00e1bado 5 de noviembre a las 16:00 en\u00a0<a href=\"http:\/\/www.trixilxes.com\/\">www.trixilxes.com<\/a>para inscribiros en la 8\u00aa edici\u00f3n de la TriXilxes.<\/p>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes.jpeg\" title=\"Trixilxes\" alt=\"Trixilxes\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes.jpeg 1600w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-300x200.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-1024x682.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-768x512.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-1536x1023.jpeg 1536w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/Trixilxes-18x12.jpeg 18w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1361"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1361\/revisions"}],"predecessor-version":[{"id":1364,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1361\/revisions\/1364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1362"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}