{"id":1284,"date":"2024-08-19T15:13:42","date_gmt":"2024-08-19T15:13:42","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1284"},"modified":"2024-09-19T18:02:33","modified_gmt":"2024-09-19T18:02:33","slug":"xilxes-la-llosa-y-alfondenguilla-aprueban-la-creacion-de-la-mancomunidad-plana-baixa-para-mejorar-la-gestion-de-servicios-sociales-en-sus-municipios","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/xilxes-la-llosa-y-alfondenguilla-aprueban-la-creacion-de-la-mancomunidad-plana-baixa-para-mejorar-la-gestion-de-servicios-sociales-en-sus-municipios\/","title":{"rendered":"Xilxes, La Llosa i Alfondenguilla aproven la creaci\u00f3 de la Mancomunitat Plana Baixa per millorar la gesti\u00f3 de Serveis Socials als seus municipis"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1284\" data-postid=\"1284\" class=\"themify_builder_content themify_builder_content-1284 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><b>A l&#039;assemblea celebrada aquest dimarts amb la participaci\u00f3 de les tres corporacions s&#039;ha votat per unanimitat el nomenament de l&#039;alcalde de Xilxes, Jos\u00e9 Mart\u00ednez, com a president de la Mancomunitat\u00a0<\/b><\/p>\n<p class=\"western\" align=\"justify\">\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>Els regidors i regidores de Xilxes, La Llosa i Alfondenguilla han participat aquest dimarts al sal\u00f3 de plens de l&#039;Ajuntament de Xilxes en una assemblea on s&#039;han aprovat provisionalment els estatuts i la mem\u00f2ria justificativa d&#039;aquesta associaci\u00f3 conformada pels tres municipis i s&#039;ha designat la presid\u00e8ncia de la Mancomunitat Plana Ba.<\/p>\n<p>\u00a0<\/p>\n<p>Els representants de les localitats han aprovat de manera provisional la mem\u00f2ria justificativa i el projecte destatuts de la Mancomunitat Plana Baixa, que durant el termini dun mes estaran sotmesos a informaci\u00f3 p\u00fablica.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>La sessi\u00f3 tamb\u00e9 ha elegit per unanimitat l&#039;alcalde de Xilxes, Jos\u00e9 Mart\u00ednez, com a president de la mancomunitat i els primers regidors de La Llosa, Joaqu\u00edn Jos\u00e9 Llopis, i d&#039;Alfondenguilla, Salvador Ventura, com a vicepresidents. Aix\u00ed, durant la presid\u00e8ncia de Mart\u00ednez, tant la capitalitat de la mancomunitat com els \u00f2rgans de govern i administraci\u00f3 s&#039;ubicaran a Xilxes, tenint com a domicili social i lloc de reuni\u00f3 el seu Ajuntament.<\/p>\n<p>\u00a0<\/p>\n<p>Amb la creaci\u00f3 de la Mancomunitat Plana Baixa, els tres municipis tenen com a objectiu compartir les compet\u00e8ncies relacionades amb l&#039;\u00e0rea de serveis socials d&#039;atenci\u00f3 prim\u00e0ria de car\u00e0cter b\u00e0sic i gestionar conjuntament tasques com l&#039;avaluaci\u00f3 i la informaci\u00f3 de situacions de necessitat social o l&#039;atenci\u00f3 immediata a persones en situaci\u00f3 o risc d&#039;exclusi\u00f3 social. A m\u00e9s, entre els fins de l&#039;ens local territorial tamb\u00e9 hi ha la reactivaci\u00f3 econ\u00f2mica i demogr\u00e0fica dels municipis que la integren i la realitzaci\u00f3 de les iniciatives que ajudin els interessos generals dels seus territoris.\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD.jpeg\" class=\"wp-post-image wp-image-1285\" title=\"MANCOMUNITAT\" alt=\"MANCOMUNIDAD\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-300x225.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-768x576.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-16x12.jpeg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1285,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><b>En la asamblea celebrada este martes con la participaci\u00f3n de las tres corporaciones se ha votado por unanimidad el nombramiento del alcalde de Xilxes, Jos\u00e9 Mart\u00ednez, como presidente de la Mancomunidad\u00a0<\/b><\/p> <p align=\"justify\">\u00a0<\/p>\n<p>Los concejales y concejalas\u00a0de Xilxes, La Llosa y Alfondenguilla han participado este martes en el sal\u00f3n de plenos del Ayuntamiento de Xilxes en una asamblea en la que se han aprobado provisionalmente los estatutos y la memoria justificativa de esta asociaci\u00f3n conformada por los tres municipios y se ha\u00a0designado\u00a0la presidencia de la Mancomunidad Plana Baixa.<\/p> <p>\u00a0<\/p> <p>Los representantes de las localidades han aprobado de manera provisional la memoria justificativa y el proyecto de estatutos de la Mancomunidad Plana Baixa, que durante el plazo de un mes estar\u00e1n sometidos a informaci\u00f3n p\u00fablica.\u00a0<\/p> <p>\u00a0<\/p> <p>La sesi\u00f3n tambi\u00e9n ha elegido por unanimidad\u00a0al alcalde de Xilxes, Jos\u00e9 Mart\u00ednez, como presidente de la mancomunidad y a los primeros ediles de La Llosa, Joaqu\u00edn Jos\u00e9 Llopis, y de Alfondenguilla, Salvador Ventura, como vicepresidentes. As\u00ed, durante la presidencia de Mart\u00ednez,\u00a0tanto\u00a0la capitalidad de la mancomunidad como los \u00f3rganos de gobierno y administraci\u00f3n se ubicar\u00e1n en Xilxes, teniendo como domicilio social y lugar de reuni\u00f3n su Ayuntamiento.<\/p> <p>\u00a0<\/p> <p>Con la creaci\u00f3n de la Mancomunidad Plana Baixa, los tres municipios tienen como objetivo compartir las competencias relacionadas con el \u00e1rea de Servicios Sociales de atenci\u00f3n primaria de car\u00e1cter b\u00e1sico y gestionar conjuntamente tareas como la evaluaci\u00f3n e informaci\u00f3n de situaciones de necesidad social o la atenci\u00f3n inmediata a personas en situaci\u00f3n o riesgo de exclusi\u00f3n social. Adem\u00e1s, entre los fines del ente local territorial tambi\u00e9n est\u00e1n la reactivaci\u00f3n econ\u00f3mica y demogr\u00e1fica de los municipios que la integran y la realizaci\u00f3n de las iniciativas que ayuden a los intereses generales de sus territorios.\u00a0<\/p>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD.jpeg\" title=\"MANCOMUNIDAD\" alt=\"MANCOMUNIDAD\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD.jpeg 1024w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-300x225.jpeg 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-768x576.jpeg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/MANCOMUNIDAD-16x12.jpeg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1287,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}