{"id":1219,"date":"2024-08-31T14:56:19","date_gmt":"2024-08-31T14:56:19","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1219"},"modified":"2024-09-19T18:05:01","modified_gmt":"2024-09-19T18:05:01","slug":"inicio-del-plazo-de-solicitud-para-ocupar-los-puestos-de-socorristas-y-operarios-de-playas-accesibles-en-xilxes","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/inicio-del-plazo-de-solicitud-para-ocupar-los-puestos-de-socorristas-y-operarios-de-playas-accesibles-en-xilxes\/","title":{"rendered":"Inici del termini de sol\u00b7licitud per ocupar els llocs de socorristes i operaris de platges accessibles a Xilxes"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1219\" data-postid=\"1219\" class=\"themify_builder_content themify_builder_content-1219 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p><strong>El termini de sol\u00b7licituds \u00e9s del 24 d&#039;abril fins al proper 8 de maig del 2023, tota la informaci\u00f3 sobre les dues convocat\u00f2ries es pot consultar a trav\u00e9s de la seu electr\u00f2nica de l&#039;Ajuntament a www.xilxes.es<\/strong><\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module text -->\n<div  class=\"module module-text tb_lczc376\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>El Butllet\u00ed Oficial de la Prov\u00edncia de Castell\u00f3 ha publicat aquest dilluns les bases de la convocat\u00f2ria per a l&#039;ocupaci\u00f3 dels llocs de socorrista (12 places) i operari de platja accessible (4 places), totes dues amb car\u00e0cter laboral temporal. Tota la informaci\u00f3 sobre les proves selectives per a la contractaci\u00f3 del personal a realitzar mitjan\u00e7ant sistema de concurs oposici\u00f3 estan disponibles a la seu electr\u00f2nica de l&#039;Ajuntament a\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p>La distribuci\u00f3 i tasques del personal en la prestaci\u00f3 del servei de socorrisme a platges i\/o piscina municipal, pel temps necessari, s&#039;efectuaran en funci\u00f3 de les necessitats del mateix. Daltra banda, les funcions del lloc doperari de platja accessible corresponen amb el servei dassist\u00e8ncia a persones amb mobilitat redu\u00efda, organitzaci\u00f3 i manteniment de la zona accessible durant el per\u00edode estival, pel termini de tres mesos.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Els aspirants dambdues borses de treball hauran de complir amb una s\u00e8rie de requisits exposats a les bases, on tamb\u00e9 figuren les especificacions sobre la fase doposici\u00f3, en la qual es duran a terme diferents proves f\u00edsiques i escrites, i la fase de concurs, en la qual es valoraran diferents m\u00e8rits acad\u00e8mics i dexperi\u00e8ncia professional.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>El termini per a la presentaci\u00f3 de les sol\u00b7licituds \u00e9s des del 24 d&#039;abril fins al 8 de maig del 2023, ambd\u00f3s dies inclosos.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"370\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670.png\" class=\"wp-post-image wp-image-1220\" title=\"f0d62d1961141fcfed6108fd9e0f2670\" alt=\"f0d62d1961141fcfed6108fd9e0f2670\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670.png 555w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670-300x200.png 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670-18x12.png 18w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1220,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p><strong>El plazo de solicitudes es del 24 de abril hasta el pr\u00f3ximo 8 de mayo de 2023, toda la informaci\u00f3n sobre ambas convocatorias se puede consultar a trav\u00e9s de la sede electr\u00f3nica del Ayuntamiento en www.xilxes.es<\/strong><\/p>\n<p>El Bolet\u00edn Oficial de la Provincia de Castell\u00f3n ha publicado este lunes las bases de la convocatoria para la ocupaci\u00f3n de los puestos de socorrista (12 plazas), y operario de playa accesible (4 plazas), ambas con car\u00e1cter laboral temporal. Toda la informaci\u00f3n sobre las pruebas selectivas para la contrataci\u00f3n del personal a realizar mediante sistema de concurso-oposici\u00f3n est\u00e1n disponibles en la sede electr\u00f3nica del Ayuntamiento en\u00a0<a href=\"http:\/\/www.xilxes.es\/\">www.xilxes.es<\/a>.<\/p> <p>\u00a0<\/p> <p>La distribuci\u00f3n y tareas del personal en la prestaci\u00f3n del servicio de socorrismo en playas y\/o piscina municipal, por el tiempo necesario, se efectuar\u00e1n en funci\u00f3n de las necesidades del mismo. Por otro lado, las funciones del puesto de operario de playa accesible corresponden con el servicio de asistencia a personas con movilidad reducida, organizaci\u00f3n y mantenimiento de la zona accesible durante el periodo estival, por el plazo de tres meses.\u00a0<\/p> <p>\u00a0<\/p> <p>Los aspirantes de ambas bolsas de trabajo deber\u00e1n cumplir con una serie de requisitos expuestos en las bases, donde tambi\u00e9n figuran las especificaciones acerca de la fase de oposici\u00f3n, en la cual se llevar\u00e1n a cabo distintas pruebas f\u00edsicas y escritas, y la fase de concurso, en la que se valorar\u00e1n diferentes m\u00e9ritos acad\u00e9micos y de experiencia profesional.\u00a0<\/p> <p>\u00a0<\/p> <p>El plazo para la presentaci\u00f3n de las solicitudes es desde el 24 de abril hasta el 8 de mayo de 2023, ambos d\u00edas incluidos.<\/p>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670.png\" title=\"f0d62d1961141fcfed6108fd9e0f2670\" alt=\"f0d62d1961141fcfed6108fd9e0f2670\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670.png 555w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670-300x200.png 300w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/f0d62d1961141fcfed6108fd9e0f2670-18x12.png 18w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1219"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1219\/revisions"}],"predecessor-version":[{"id":1222,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1219\/revisions\/1222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1220"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}