{"id":1170,"date":"2024-06-19T14:44:46","date_gmt":"2024-06-19T14:44:46","guid":{"rendered":"https:\/\/ayto3.accesia.info\/?p=1170"},"modified":"2024-09-19T18:06:39","modified_gmt":"2024-09-19T18:06:39","slug":"chilches-aprueba-el-programa-de-fiestas-del-cristo-y-actuaciones-de-mantenimiento","status":"publish","type":"post","link":"https:\/\/ayto3.accesia.info\/ca\/chilches-aprueba-el-programa-de-fiestas-del-cristo-y-actuaciones-de-mantenimiento\/","title":{"rendered":"Chilches aprova el programa de Festes del Crist i actuacions de manteniment"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-1170\" data-postid=\"1170\" class=\"themify_builder_content themify_builder_content-1170 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vlbg496 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_2riz496 first\">\n                    <!-- module text -->\n<div  class=\"module module-text tb_9poi149\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <p>Durant el ple ordinari, celebrat el passat dijous 31 d&#039;agost, l&#039;Ajuntament de Xilxes\/Xilxes ha aprovat en ple la programaci\u00f3 de les\u00a0<strong>Festes en honor del Sant\u00edssim Crist de la Jonquera 2023<\/strong>, que se celebraran del\u00a0<strong>15 al 24 de setembre<\/strong>.\u00a0<\/p>\n<p>Aix\u00ed mateix, la sessi\u00f3 plen\u00e0ria ha donat llum verda a altres assumptes com s\u00f3n la modificaci\u00f3 de cr\u00e8dits per a aquest 2023, permetent executar tasques de pintura i manteniment dels edificis p\u00fablics, com s\u00f3n, Ajuntament, Biblioteca, Front\u00f3, Sala Multiusos, Gimn\u00e0s, Magatzem i bar L&#039;Alter.<\/p>\n<p>Tamb\u00e9 es va acordar ampliar una partida per a la neteja de camins i s\u00e8quies, aix\u00ed com el manteniment de la m\u00e0quina escombraria municipal i una partida per a les festes.<\/p>    <\/div>\n<\/div>\n<!-- \/module text --><!-- module image -->\n<div  class=\"module module-image tb_tov0391 image-top   tf_mw\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1016\" height=\"1024\" src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO.jpg\" class=\"wp-post-image wp-image-1171\" title=\"PLE\" alt=\"PLENO\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO.jpg 1016w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-298x300.jpg 298w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-150x150.jpg 150w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-768x774.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-12x12.jpg 12w\" sizes=\"auto, (max-width: 1016px) 100vw, 1016px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <\/div>\n<!-- \/module image -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1171,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<p>Durante el pleno ordinario, celebrado el pasado jueves 31 de agosto, el Ayuntamiento de Chilches\/Xilxes ha aprobado en pleno la programaci\u00f3n de las\u00a0<strong>Fiestas en honor del Sant\u00edsimo Cristo de la Junquera 2023<\/strong>, que se celebrar\u00e1n del\u00a0<strong>15 al 24 de septiembre<\/strong>.\u00a0<\/p> <p>As\u00ed mismo, la sesi\u00f3n plenaria ha dado luz verde a otros asuntos como son la modificaci\u00f3n de cr\u00e9ditos para este 2023, permitiendo ejecutar tareas de pintura y mantenimiento de los edificios p\u00fablicos, como son, Ayuntamiento, Biblioteca, Front\u00f3n, Sala Multiusos, Gimnasio, Almac\u00e9n y bar El l'Alter.<\/p> <p>Tambi\u00e9n se acord\u00f3 ampliar una partida para la limpieza de caminos y acequias, as\u00ed como el mantenimiento de la m\u00e1quina barrendera municipal y una partida para las fiestas.<\/p>\n<img src=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO.jpg\" title=\"PLENO\" alt=\"PLENO\" srcset=\"https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO.jpg 1016w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-298x300.jpg 298w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-150x150.jpg 150w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-768x774.jpg 768w, https:\/\/ayto3.accesia.info\/wp-content\/uploads\/2024\/09\/PLENO-12x12.jpg 12w\" sizes=\"(max-width: 1016px) 100vw, 1016px\" \/>","_links":{"self":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/comments?post=1170"}],"version-history":[{"count":2,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1170\/revisions"}],"predecessor-version":[{"id":1173,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/posts\/1170\/revisions\/1173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media\/1171"}],"wp:attachment":[{"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/media?parent=1170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/categories?post=1170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ayto3.accesia.info\/ca\/wp-json\/wp\/v2\/tags?post=1170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}